{"id":6283,"date":"2014-11-06T16:00:28","date_gmt":"2014-11-06T19:00:28","guid":{"rendered":"http:\/\/www.trocandofraldas.com.br\/?p=6283"},"modified":"2023-10-23T09:54:28","modified_gmt":"2023-10-23T12:54:28","slug":"espermograma-completo-procedimento-rapido-e-sem-constrangimentos","status":"publish","type":"post","link":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/","title":{"rendered":"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos"},"content":{"rendered":"<p class=\"align-justify\">Quando um casal resolve que chegou a hora de aumentar a fam\u00edlia e ap\u00f3s meses e meses de tentativa n\u00e3o consegue, a primeira coisa que passa na cabe\u00e7a \u00e9 que a mulher n\u00e3o pode ter filhos e precisa procurar um m\u00e9dico para fazer exames e ver o que est\u00e1 acontecendo.<\/p>\n<p class=\"align-justify\">Depois de realizar todos os exames e n\u00e3o constatar nada, nenhuma irregularidade, o que pode estar acontecendo? O problema pode estar no homem. Ent\u00e3o talvez seja necess\u00e1rio fazer um espermograma completo ap\u00f3s a solicita\u00e7\u00e3o de um m\u00e9dico para verificar o problema e por que <a href=\"https:\/\/www.famivita.com\/pt\/nao-consigo-engravidar-como-descobrir-causa\/\" target=\"_self\" rel=\"noopener noreferrer\">n\u00e3o conseguem engravidar<\/a>.<\/p>\n<p class=\"align-justify\">Para a mulher conseguir engravidar, os espermatozoides do homem precisam ter condi\u00e7\u00f5es para chegar e fecundar o \u00f3vulo feminino. Para isso serve o exame de espermograma completo, para verificar se esses espermatozoides t\u00eam condi\u00e7\u00f5es e for\u00e7a e se s\u00e3o saud\u00e1veis o suficiente para conseguir chegar at\u00e9 o \u00f3vulo.<\/p>\n<p class=\"align-justify\">Atrav\u00e9s do espermograma completo se avalia a <strong>qualidade do s\u00eamen<\/strong>, a quantidade e as condi\u00e7\u00f5es f\u00edsicas e qu\u00edmicas dele. Esse exame servir\u00e1 para o casal ter um diagn\u00f3stico do que est\u00e1 acontecendo e, quando constatado algum problema, reverter a situa\u00e7\u00e3o atrav\u00e9s de um tratamento adequado.<\/p>\n<h2>Quando \u00e9 Indicado o Espermograma Completo e Onde \u00e9 Feito?<\/h2>\n<p class=\"align-justify\">Normalmente, o espermograma completo \u00e9 solicitado quando est\u00e1 sendo realizada a investiga\u00e7\u00e3o da infertilidade do casal ou do homem. Ou at\u00e9 mesmo quando j\u00e1 se sabe que o homem \u00e9 est\u00e9ril, mas \u00e9 necess\u00e1rio saber o motivo dessa infertilidade e se \u00e9 poss\u00edvel revert\u00ea-la<a class=\"jumpToggle\" data-jumpto=\"source1\"><sup>1<\/sup><\/a>.<\/p>\n<p class=\"align-justify\">No exame o material \u00e9 todo analisado, sendo examinados a qualidade, o cheiro, a quantidade e o<strong> PH do espermatozoide<\/strong>. O exame de espermograma completo \u00e9 feito em um laborat\u00f3rio especializado e o estudo \u00e9 todo feito atrav\u00e9s da utiliza\u00e7\u00e3o de uma aparelhagem adequada, como o microsc\u00f3pio, que conseguir\u00e1 visualizar minuciosamente cada detalhe do s\u00eamen. Dessa forma \u00e9 poss\u00edvel fazer uma compara\u00e7\u00e3o com o que \u00e9 considerado normal para ent\u00e3o se ter um diagn\u00f3stico correto e preciso.<\/p>\n<div align=\"center\"><a rel=\"nofollow\" target=\"_blank\" class=\"iframe-ytube-link\" href=\"https:\/\/www.youtube.com\/embed\/UciDWWH8dlY?showinfo=0&autoplay=1\" data-height=\"270\" data-width=\"480\" data-tagmanagerid=\"\"><img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/UciDWWH8dlY\/0.jpg\"  class=\"youtube_video_banner\"><span class=\"utuve-vdo-icon\"><\/span><\/a><\/div>\n<p>As altera\u00e7\u00f5es possivelmente encontradas na an\u00e1lise do s\u00eamen realizada pelo espermograma completo s\u00e3o:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.famivita.com\/pt\/oligospermia-o-que-e-como-tratar\/\" target=\"_self\" rel=\"noopener noreferrer\">Oligospermia<\/a> &#8211; \u00a0N\u00famero abaixo da normalidade de espermatozoides<\/li>\n<li>Astenospermia &#8211; Dificuldade de chegar ate o \u00f3vulo<\/li>\n<li><a href=\"https:\/\/www.famivita.com\/pt\/necrospermia\/\">Necrospermia<\/a> &#8211; Grande parte dos espermatozoides mortos<\/li>\n<li><a href=\"https:\/\/www.famivita.com\/pt\/infertilidade-masculina-espermograma-principais-problemas\/\">Teratospermia<\/a> &#8211; Formato dos espermatozoides diferente do considerado normal<\/li>\n<\/ul>\n<p class=\"align-justify\">Outros problemas e altera\u00e7\u00f5es que podem ser encontrados no espermograma completo s\u00e3o a azoospermia<a class=\"jumpToggle\" data-jumpto=\"source2\"><sup>2<\/sup><\/a>, que \u00e9 a aus\u00eancia total de espermatozoides, a oligo astenospermia, que \u00e9 a diminui\u00e7\u00e3o na quantidade e a dificuldade deles chegarem ate o \u00f3vulo, e a leucospermia, que \u00e9 a presen\u00e7a de um grande n\u00famero de leuc\u00f3citos no l\u00edquido seminal, podendo ser um sinal de alguma infec\u00e7\u00e3o que dever\u00e1 ser tratada.<\/p>\n<p class=\"align-justify\">O exame ser\u00e1 realizado com <strong>total privacidade<\/strong>, sendo solicitada uma amostra de s\u00eamen dentro de um frasco de coleta. O homem ficar\u00e1 dentro de uma sala sozinho, e ter\u00e1 o tempo que for necess\u00e1rio para conseguir efetuar a coleta do material. Geralmente as cl\u00ednicas e laborat\u00f3rios d\u00e3o uma forcinha para o homem disponibilizando materiais er\u00f3ticos para facilitar o procedimento.<\/p>\n<p class=\"align-justify\">Alguns laborat\u00f3rios hoje em dia permitem que a coleta seja realizada na resid\u00eancia, desde que seguidas algumas normas de higiene, esteriliza\u00e7\u00e3o e tempo para entrega do material.<\/p>\n<p class=\"align-justify\">O material para exame do espermograma completo deve ser entregue at\u00e9 30 minutos ap\u00f3s a coleta. Ap\u00f3s esse per\u00edodo, o s\u00eamen \u00e9 considerado inv\u00e1lido para verifica\u00e7\u00e3o.\u00a0A prepara\u00e7\u00e3o para o exame de espermograma completo \u00e9 de <strong>abstin\u00eancia sexual<\/strong> m\u00ednima de 5 dias. Quanto a higiene antes da coleta, as m\u00e3os devem ser lavadas com sab\u00e3o e \u00e1gua em abund\u00e2ncia para ficarem totalmente livre de bact\u00e9rias.<\/p>\n<p class=\"align-justify\">Algumas restri\u00e7\u00f5es alimentares podem ser solicitadas pelo m\u00e9dico, e dever\u00e3o ser seguidas pelo prazo m\u00ednimo de 5 a 7 dias antes da coleta. Al\u00e9m disso, a coleta nunca deve ser feita com a ajuda de preservativos, pois eles cont\u00eam espermicidas que alteram o resultado do exame, al\u00e9m da exist\u00eancia de outras subst\u00e2ncias, como o lubrificante.<\/p>\n<p class=\"align-justify\">Se mesmo depois de todos os exames for conclu\u00eddo que n\u00e3o existe a possibilidade de engravidar naturalmente, por que n\u00e3o optar pela fertiliza\u00e7\u00e3o in vitro ou insemina\u00e7\u00e3o artificial<a class=\"jumpToggle\" data-jumpto=\"source3\"><sup>3<\/sup><\/a>? Dessa forma seu sonho ser\u00e1 realizado talvez mais r\u00e1pido do que voc\u00ea imagina.<\/p>\n<p class=\"align-justify\">Veja tamb\u00e9m: <a href=\"https:\/\/www.famivita.com\/pt\/infertilidade-masculina-espermograma-principais-problemas\/\" target=\"_self\" rel=\"noopener noreferrer\">Infertilidade Masculina e Espermograma \u2013 Quais os Principais Problemas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O espermograma auxilia no descobrimento de uma poss\u00edvel infertilidade ou ate mesmo de um pequeno problema que poder\u00e1 ser resolvido atrav\u00e9s de tratamento.<\/p>\n","protected":false},"author":471399,"featured_media":6287,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[979,1057,659],"tags":[46,842,39],"class_list":["post-6283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dificuldades-para-engravidar","category-exames-para-engravidar","category-tentantes","tag-espermatozoide","tag-exames","tag-gravidez-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos | Famivita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos | Famivita\" \/>\n<meta property=\"og:description\" content=\"O espermograma auxilia no descobrimento de uma poss\u00edvel infertilidade ou ate mesmo de um pequeno problema que poder\u00e1 ser resolvido atrav\u00e9s de tratamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Famivita\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-06T19:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T12:54:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. Mayara Belli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dra. Mayara Belli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/\",\"url\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/\",\"name\":\"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos | Famivita\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/#website\",\"sameAs\":[\"https:\/\/www.instagram.com\/famivita\/\",\"https:\/\/www.facebook.com\/famivita\/\",\"https:\/\/www.youtube.com\/user\/trocandofraldasyt\",\"https:\/\/api.whatsapp.com\/send\/?phone=5511917837433\"]},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg\",\"datePublished\":\"2014-11-06T19:00:28+00:00\",\"dateModified\":\"2023-10-23T12:54:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/\"]}],\"about\":{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.famivita.com.br\/#organization\",\"name\":\"Famivita\",\"logo\":\"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg\",\"url\":\"https:\/\/www.famivita.com.br\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rua Benedito Fernandes, 545, Santo Amaro\",\"addressLocality\":\"S\u00e3o Paulo\",\"addressRegion\":\"S\u00e3o Paulo\",\"postalCode\":\"04746-110\",\"addressCountry\":{\"@type\":\"Country\",\"name\":\"BR\"}}}},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#primaryimage\",\"url\":\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg\",\"width\":595,\"height\":480,\"caption\":\"\u00c9 verificado atrav\u00e9s de microsc\u00f3pio a quantidade e caracter\u00edsticas do espermatozoide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.famivita.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tentantes\",\"item\":\"https:\/\/www.famivita.com\/pt\/categoria\/tentantes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dificuldades para Engravidar\",\"item\":\"https:\/\/www.famivita.com\/pt\/categoria\/dificuldades-para-engravidar\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Exames para Engravidar\",\"item\":\"https:\/\/www.famivita.com\/pt\/categoria\/exames-para-engravidar\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.famivita.com\/pt\/#website\",\"url\":\"https:\/\/www.famivita.com\/pt\/\",\"name\":\"Famivita\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.famivita.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c\",\"name\":\"Dra. Mayara Belli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"caption\":\"Dra. Mayara Belli\"},\"description\":\"Graduada em Nutri\u00e7\u00e3o pela Universidade Anhembi Morumbi. \u00c9 p\u00f3s-graduada em Nutri\u00e7\u00e3o Materno Infantil e possui forma\u00e7\u00e3o em Nutri\u00e7\u00e3o e Fertilidade. Possui, tamb\u00e9m, forma\u00e7\u00e3o em Natural Chef (gastronomia funcional) e hoje \u00e9 atuante na \u00e1rea cl\u00ednica de atendimento nutricional \u00e0s tentantes, casais, gestantes, lactantes, crian\u00e7as e sa\u00fade da mulher.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nutri.futuramamae\/\"],\"url\":\"https:\/\/www.famivita.com\/pt\/author\/dra-mayara-belli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos | Famivita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/","og_locale":"pt_PT","og_type":"article","og_title":"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos | Famivita","og_description":"O espermograma auxilia no descobrimento de uma poss\u00edvel infertilidade ou ate mesmo de um pequeno problema que poder\u00e1 ser resolvido atrav\u00e9s de tratamento.","og_url":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/","og_site_name":"Famivita","article_published_time":"2014-11-06T19:00:28+00:00","article_modified_time":"2023-10-23T12:54:28+00:00","og_image":[{"width":595,"height":480,"url":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg","type":"image\/jpeg"}],"author":"Dra. Mayara Belli","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dra. Mayara Belli","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/","url":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/","name":"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos | Famivita","isPartOf":{"@id":"https:\/\/www.famivita.com\/pt\/#website","sameAs":["https:\/\/www.instagram.com\/famivita\/","https:\/\/www.facebook.com\/famivita\/","https:\/\/www.youtube.com\/user\/trocandofraldasyt","https:\/\/api.whatsapp.com\/send\/?phone=5511917837433"]},"primaryImageOfPage":{"@id":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#primaryimage"},"image":{"@id":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg","datePublished":"2014-11-06T19:00:28+00:00","dateModified":"2023-10-23T12:54:28+00:00","author":{"@id":"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c"},"breadcrumb":{"@id":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/"]}],"about":{"@type":"Organization","@id":"https:\/\/www.famivita.com.br\/#organization","name":"Famivita","logo":"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg","url":"https:\/\/www.famivita.com.br\/","address":{"@type":"PostalAddress","streetAddress":"Rua Benedito Fernandes, 545, Santo Amaro","addressLocality":"S\u00e3o Paulo","addressRegion":"S\u00e3o Paulo","postalCode":"04746-110","addressCountry":{"@type":"Country","name":"BR"}}}},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#primaryimage","url":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg","contentUrl":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/espermograma-completo-1.jpg","width":595,"height":480,"caption":"\u00c9 verificado atrav\u00e9s de microsc\u00f3pio a quantidade e caracter\u00edsticas do espermatozoide"},{"@type":"BreadcrumbList","@id":"https:\/\/www.famivita.com\/pt\/espermograma-completo-procedimento-rapido-e-sem-constrangimentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.famivita.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Tentantes","item":"https:\/\/www.famivita.com\/pt\/categoria\/tentantes\/"},{"@type":"ListItem","position":3,"name":"Dificuldades para Engravidar","item":"https:\/\/www.famivita.com\/pt\/categoria\/dificuldades-para-engravidar\/"},{"@type":"ListItem","position":4,"name":"Exames para Engravidar","item":"https:\/\/www.famivita.com\/pt\/categoria\/exames-para-engravidar\/"},{"@type":"ListItem","position":5,"name":"Espermograma Completo \u2013 Procedimento R\u00e1pido e sem Constrangimentos"}]},{"@type":"WebSite","@id":"https:\/\/www.famivita.com\/pt\/#website","url":"https:\/\/www.famivita.com\/pt\/","name":"Famivita","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.famivita.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c","name":"Dra. Mayara Belli","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","contentUrl":"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","caption":"Dra. Mayara Belli"},"description":"Graduada em Nutri\u00e7\u00e3o pela Universidade Anhembi Morumbi. \u00c9 p\u00f3s-graduada em Nutri\u00e7\u00e3o Materno Infantil e possui forma\u00e7\u00e3o em Nutri\u00e7\u00e3o e Fertilidade. Possui, tamb\u00e9m, forma\u00e7\u00e3o em Natural Chef (gastronomia funcional) e hoje \u00e9 atuante na \u00e1rea cl\u00ednica de atendimento nutricional \u00e0s tentantes, casais, gestantes, lactantes, crian\u00e7as e sa\u00fade da mulher.","sameAs":["https:\/\/www.instagram.com\/nutri.futuramamae\/"],"url":"https:\/\/www.famivita.com\/pt\/author\/dra-mayara-belli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts\/6283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/users\/471399"}],"replies":[{"embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/comments?post=6283"}],"version-history":[{"count":12,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts\/6283\/revisions"}],"predecessor-version":[{"id":159669,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts\/6283\/revisions\/159669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/media\/6287"}],"wp:attachment":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/media?parent=6283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/categories?post=6283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/tags?post=6283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}