{"id":7048,"date":"2015-02-22T10:00:07","date_gmt":"2015-02-22T13:00:07","guid":{"rendered":"http:\/\/www.trocandofraldas.com.br\/?p=7048"},"modified":"2023-10-23T09:38:52","modified_gmt":"2023-10-23T12:38:52","slug":"exame-streptococcus-qual-necessidade","status":"publish","type":"post","link":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/","title":{"rendered":"Exame Streptococcus \u2013 Qual a Necessidade?"},"content":{"rendered":"<p class=\"align-justify\">O streptococcus<a class=\"jumpToggle\" data-jumpto=\"source1\"><sup>1<\/sup><\/a> \u00e9 uma bact\u00e9ria que normalmente se encontra na <strong>regi\u00e3o da boca<\/strong>, por esse motivo a transmiss\u00e3o ocorre de forma natural atrav\u00e9s do beijo, do compartilhamento de objetos como talher e copos. Por fazer parte da boca, facilita o alojamento em nosso intestino e no sistema respirat\u00f3rio e s\u00e3o respons\u00e1veis por grande parte das doen\u00e7as desde uma carie dentaria ate uma pneumonia.<\/p>\n<h3>Streptococcus B<\/h3>\n<p class=\"align-justify\">Isso porque existem diversos tipos de streptococcus e cada um deles respons\u00e1vel por um tipo de doen\u00e7a. Neste caso, falaremos sobre o <strong>streptococcus do grupo B<\/strong> que \u00e9 o investigado na gesta\u00e7\u00e3o atrav\u00e9s do <a href=\"https:\/\/www.famivita.com\/pt\/colo-do-utero-e-teste-do-cotonete-como-fazer\/\" target=\"_self\" rel=\"noopener\">exame do cotonete<\/a>.<\/p>\n<p class=\"align-justify\">O streptococcus B costuma se colonizar em regi\u00f5es<strong> vaginais, intestinais e retais femininas<\/strong>. N\u00e3o apresenta riscos a pessoas saud\u00e1veis, mas podem trazer complica\u00e7\u00f5es na transmiss\u00e3o de m\u00e3e para filho na hora do nascimento. Por isso a import\u00e2ncia do exame antes da realiza\u00e7\u00e3o do parto, sendo um m\u00e9todo de preven\u00e7\u00e3o e de prote\u00e7\u00e3o para o beb\u00ea<a class=\"jumpToggle\" data-jumpto=\"source2\"><sup>2<\/sup><\/a>.<\/p>\n<p class=\"align-justify\">Ao contr\u00e1rio do que a maioria acredita o streptococcus B n\u00e3o \u00e9 uma doen\u00e7a sexualmente transmiss\u00edvel. A \u00e1rea vaginal normalmente \u00e9 contaminada pelas bact\u00e9rias deslocadas do pr\u00f3prio intestino e da regi\u00e3o retal, por isso n\u00e3o se assuste caso o resultado do seu exame d\u00ea positivo.<\/p>\n<h2>O Exame deu Positivo o que Fa\u00e7o Agora?<\/h2>\n<p class=\"align-justify\">O exame \u00e9 realizado de forma simples no pr\u00f3prio consult\u00f3rio, sendo coletadas amostras da regi\u00e3o da<strong> vagina e do \u00e2nus<\/strong> com a ajuda de um equipamento parecido com um cotonete, por isso ganhou o nome popular de \u201cexame do cotonete\u201d. O exame \u00e9 solicitado entre a 35\u00ba e 37\u00ba semana de gesta\u00e7\u00e3o, quando esta mais pr\u00f3xima do nascimento.<\/p>\n<h3>Tratamento<\/h3>\n<p class=\"align-justify\">O resultado sair\u00e1 ap\u00f3s alguns dias e caso positivo, n\u00e3o ser\u00e1 recomendado nenhum tratamento, nem a base de pomadas vaginais e nem rem\u00e9dios. A administra\u00e7\u00e3o de medicamento ser\u00e1 realizada algumas horas antes do parto, normalmente em media <strong>4 horas antes<\/strong>, diretamente na maternidade. O medicamento utilizado para combater \u00e9 o antibi\u00f3tico e deve ser introduzido pela veia, para que sua efic\u00e1cia seja imediata<a class=\"jumpToggle\" data-jumpto=\"source3\"><sup>3<\/sup><\/a>.<\/p>\n<h3>Carteirinha de Pr\u00e9-Natal<\/h3>\n<p class=\"align-justify\">O resultado do exame dever\u00e1 constar na <strong>carteirinha de pr\u00e9-natal<\/strong> que ser\u00e1 solicitada na interna\u00e7\u00e3o da maternidade. Se acaso n\u00e3o estiver munido com documentos, deve-se informar ao hospital sobre o resultado do exame streptococcus para que o procedimento seja realizado o quanto antes. No caso de ces\u00e1rea n\u00e3o \u00e9 utilizada a medica\u00e7\u00e3o, j\u00e1 que o beb\u00ea n\u00e3o passar\u00e1 pelo canal vaginal n\u00e3o sendo exposto ao risco de contamina\u00e7\u00e3o.<\/p>\n<p class=\"align-justify\">Caso n\u00e3o tratado devidamente antes do parto e o beb\u00ea porventura se contaminar, pode sofrer com <strong>sepse neonatal<\/strong> que \u00e9 uma infec\u00e7\u00e3o no sangue muito perigosa que pode levar a \u00f3bito.<\/p>\n<p class=\"align-justify\">Outros problemas agravantes da falta de cuidado, \u00e9 a pneumonia e a<a href=\"https:\/\/www.famivita.com\/pt\/sintomas-de-meningite-em-bebes-como-percebe-los-o-quanto-antes\/\" target=\"_self\" rel=\"noopener\"> meningite <\/a>que por atacar j\u00e1 nas primeiras semanas de vida pode trazer s\u00e9rios riscos. O quadro mais perigoso de contagio \u00e9 para beb\u00eas prematuros, que apresentam ainda mais riscos podendo ficar com sequelas graves.<\/p>\n<p class=\"align-justify\">Veja tamb\u00e9m:\u00a0<a href=\"https:\/\/www.famivita.com\/pt\/teste-cotonete-colo-utero-video\/\" target=\"_self\" rel=\"noopener\">Teste do Cotonete e Colo do \u00datero \u2013 V\u00eddeo<\/a><\/p>\n<p class=\"align-justify\">Foto: Iqbal Osman,\u00a0Daniel Lobo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.<\/p>\n","protected":false},"author":471399,"featured_media":7050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1006,19],"tags":[833,842,39],"class_list":["post-7048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exames-na-gravidez","category-gravidez","tag-cuidados","tag-exames","tag-gravidez-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exame Streptococcus \u2013 Qual a Necessidade? | Famivita<\/title>\n<meta name=\"description\" content=\"O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exame Streptococcus \u2013 Qual a Necessidade? | Famivita\" \/>\n<meta property=\"og:description\" content=\"O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Famivita\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-22T13:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T12:38:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"448\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dra. Mayara Belli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dra. Mayara Belli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/\",\"url\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/\",\"name\":\"Exame Streptococcus \u2013 Qual a Necessidade? | Famivita\",\"isPartOf\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/#website\",\"sameAs\":[\"https:\/\/www.instagram.com\/famivita\/\",\"https:\/\/www.facebook.com\/famivita\/\",\"https:\/\/www.youtube.com\/user\/trocandofraldasyt\",\"https:\/\/api.whatsapp.com\/send\/?phone=5511917837433\"]},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg\",\"datePublished\":\"2015-02-22T13:00:07+00:00\",\"dateModified\":\"2023-10-23T12:38:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c\"},\"description\":\"O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/\"]}],\"about\":{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.famivita.com.br\/#organization\",\"name\":\"Famivita\",\"logo\":\"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg\",\"url\":\"https:\/\/www.famivita.com.br\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Rua Benedito Fernandes, 545, Santo Amaro\",\"addressLocality\":\"S\u00e3o Paulo\",\"addressRegion\":\"S\u00e3o Paulo\",\"postalCode\":\"04746-110\",\"addressCountry\":{\"@type\":\"Country\",\"name\":\"BR\"}}}},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#primaryimage\",\"url\":\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg\",\"width\":448,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.famivita.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gravidez\",\"item\":\"https:\/\/www.famivita.com\/pt\/categoria\/gravidez\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Exames na Gravidez\",\"item\":\"https:\/\/www.famivita.com\/pt\/categoria\/exames-na-gravidez\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Exame Streptococcus \u2013 Qual a Necessidade?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.famivita.com\/pt\/#website\",\"url\":\"https:\/\/www.famivita.com\/pt\/\",\"name\":\"Famivita\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.famivita.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c\",\"name\":\"Dra. Mayara Belli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"contentUrl\":\"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg\",\"caption\":\"Dra. Mayara Belli\"},\"description\":\"Graduada em Nutri\u00e7\u00e3o pela Universidade Anhembi Morumbi. \u00c9 p\u00f3s-graduada em Nutri\u00e7\u00e3o Materno Infantil e possui forma\u00e7\u00e3o em Nutri\u00e7\u00e3o e Fertilidade. Possui, tamb\u00e9m, forma\u00e7\u00e3o em Natural Chef (gastronomia funcional) e hoje \u00e9 atuante na \u00e1rea cl\u00ednica de atendimento nutricional \u00e0s tentantes, casais, gestantes, lactantes, crian\u00e7as e sa\u00fade da mulher.\",\"sameAs\":[\"https:\/\/www.instagram.com\/nutri.futuramamae\/\"],\"url\":\"https:\/\/www.famivita.com\/pt\/author\/dra-mayara-belli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exame Streptococcus \u2013 Qual a Necessidade? | Famivita","description":"O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/","og_locale":"pt_PT","og_type":"article","og_title":"Exame Streptococcus \u2013 Qual a Necessidade? | Famivita","og_description":"O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.","og_url":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/","og_site_name":"Famivita","article_published_time":"2015-02-22T13:00:07+00:00","article_modified_time":"2023-10-23T12:38:52+00:00","og_image":[{"width":448,"height":336,"url":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg","type":"image\/jpeg"}],"author":"Dra. Mayara Belli","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Dra. Mayara Belli","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/","url":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/","name":"Exame Streptococcus \u2013 Qual a Necessidade? | Famivita","isPartOf":{"@id":"https:\/\/www.famivita.com\/pt\/#website","sameAs":["https:\/\/www.instagram.com\/famivita\/","https:\/\/www.facebook.com\/famivita\/","https:\/\/www.youtube.com\/user\/trocandofraldasyt","https:\/\/api.whatsapp.com\/send\/?phone=5511917837433"]},"primaryImageOfPage":{"@id":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#primaryimage"},"image":{"@id":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#primaryimage"},"thumbnailUrl":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg","datePublished":"2015-02-22T13:00:07+00:00","dateModified":"2023-10-23T12:38:52+00:00","author":{"@id":"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c"},"description":"O streptococcus B costuma se colonizar em regi\u00f5es vaginais, intestinais e retais femininas e deve ser devidamente tratado antes do parto normal.","breadcrumb":{"@id":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/"]}],"about":{"@type":"Organization","@id":"https:\/\/www.famivita.com.br\/#organization","name":"Famivita","logo":"https:\/\/www.famivita.com.br\/wp-content\/themes\/storefront-child\/header_footer_html\/images\/logo_mobile2.svg","url":"https:\/\/www.famivita.com.br\/","address":{"@type":"PostalAddress","streetAddress":"Rua Benedito Fernandes, 545, Santo Amaro","addressLocality":"S\u00e3o Paulo","addressRegion":"S\u00e3o Paulo","postalCode":"04746-110","addressCountry":{"@type":"Country","name":"BR"}}}},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#primaryimage","url":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg","contentUrl":"https:\/\/www.famivita.com\/pt\/wp-content\/uploads\/Exame-Streptococcus-1.jpg","width":448,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/www.famivita.com\/pt\/exame-streptococcus-qual-necessidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.famivita.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Gravidez","item":"https:\/\/www.famivita.com\/pt\/categoria\/gravidez\/"},{"@type":"ListItem","position":3,"name":"Exames na Gravidez","item":"https:\/\/www.famivita.com\/pt\/categoria\/exames-na-gravidez\/"},{"@type":"ListItem","position":4,"name":"Exame Streptococcus \u2013 Qual a Necessidade?"}]},{"@type":"WebSite","@id":"https:\/\/www.famivita.com\/pt\/#website","url":"https:\/\/www.famivita.com\/pt\/","name":"Famivita","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.famivita.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/180ef97adfa38c4e31debe1d3a4b609c","name":"Dra. Mayara Belli","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.famivita.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","contentUrl":"https:\/\/www.famivita.com\/wp-content\/uploads\/2022\/08\/mayara-belli-top.jpg","caption":"Dra. Mayara Belli"},"description":"Graduada em Nutri\u00e7\u00e3o pela Universidade Anhembi Morumbi. \u00c9 p\u00f3s-graduada em Nutri\u00e7\u00e3o Materno Infantil e possui forma\u00e7\u00e3o em Nutri\u00e7\u00e3o e Fertilidade. Possui, tamb\u00e9m, forma\u00e7\u00e3o em Natural Chef (gastronomia funcional) e hoje \u00e9 atuante na \u00e1rea cl\u00ednica de atendimento nutricional \u00e0s tentantes, casais, gestantes, lactantes, crian\u00e7as e sa\u00fade da mulher.","sameAs":["https:\/\/www.instagram.com\/nutri.futuramamae\/"],"url":"https:\/\/www.famivita.com\/pt\/author\/dra-mayara-belli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts\/7048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/users\/471399"}],"replies":[{"embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/comments?post=7048"}],"version-history":[{"count":4,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts\/7048\/revisions"}],"predecessor-version":[{"id":159624,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/posts\/7048\/revisions\/159624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/media\/7050"}],"wp:attachment":[{"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/media?parent=7048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/categories?post=7048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.famivita.com\/pt\/wp-json\/wp\/v2\/tags?post=7048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}